

{"id":43,"count":6,"description":"","link":"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/","name":"Meats","slug":"carnes","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carnes archivos - El Abuelito Cheese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carnes archivos - El Abuelito Cheese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/\" \/>\n<meta property=\"og:site_name\" content=\"El Abuelito Cheese\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/categoria\\\/carnes\\\/\",\"url\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/categoria\\\/carnes\\\/\",\"name\":\"Carnes archivos - El Abuelito Cheese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/categoria\\\/carnes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/categoria\\\/carnes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carnes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/\",\"name\":\"El Abuelito Cheese\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/#organization\",\"name\":\"El Abuelito Cheese\",\"url\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abuelitocheese.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/abuelito-logo.png\",\"contentUrl\":\"https:\\\/\\\/abuelitocheese.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/abuelito-logo.png\",\"width\":618,\"height\":244,\"caption\":\"El Abuelito Cheese\"},\"image\":{\"@id\":\"https:\\\/\\\/abuelitocheese.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carnes archivos - El Abuelito Cheese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/","og_locale":"en_US","og_type":"article","og_title":"Carnes archivos - El Abuelito Cheese","og_url":"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/","og_site_name":"El Abuelito Cheese","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/","url":"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/","name":"Carnes archivos - El Abuelito Cheese","isPartOf":{"@id":"https:\/\/abuelitocheese.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/abuelitocheese.com\/en\/categoria\/carnes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/abuelitocheese.com\/en\/"},{"@type":"ListItem","position":2,"name":"Carnes"}]},{"@type":"WebSite","@id":"https:\/\/abuelitocheese.com\/en\/#website","url":"https:\/\/abuelitocheese.com\/en\/","name":"El Abuelito Cheese","description":"","publisher":{"@id":"https:\/\/abuelitocheese.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abuelitocheese.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/abuelitocheese.com\/en\/#organization","name":"El Abuelito Cheese","url":"https:\/\/abuelitocheese.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/abuelitocheese.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/abuelitocheese.com\/wp-content\/uploads\/2024\/01\/abuelito-logo.png","contentUrl":"https:\/\/abuelitocheese.com\/wp-content\/uploads\/2024\/01\/abuelito-logo.png","width":618,"height":244,"caption":"El Abuelito Cheese"},"image":{"@id":"https:\/\/abuelitocheese.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/abuelitocheese.com\/en\/wp-json\/wp\/v2\/product_cat\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abuelitocheese.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/abuelitocheese.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/abuelitocheese.com\/en\/wp-json\/wp\/v2\/product?product_cat=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}